{"id":1321447,"date":"2023-11-08T22:05:34","date_gmt":"2023-11-08T21:05:34","guid":{"rendered":"https:\/\/eu.aimcontrollers.com\/dictionary\/downloadable-content-dlc\/"},"modified":"2023-11-08T22:05:34","modified_gmt":"2023-11-08T21:05:34","slug":"downloadable-content-dlc","status":"publish","type":"dictionary","link":"https:\/\/eu.aimcontrollers.com\/de\/lexikon\/downloadable-content-dlc\/","title":{"rendered":"Downloadable Content (DLC)"},"content":{"rendered":"<p>Zus\u00e4tzlicher Inhalt f\u00fcr ein Videospiel, der \u00fcber ein digitales Liefersystem erworben wird.<\/p>\n","protected":false},"featured_media":0,"template":"","misspellings":[],"class_list":["post-1321447","dictionary","type-dictionary","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Downloadable Content (DLC) - Aimcontrollers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.aimcontrollers.com\/de\/lexikon\/downloadable-content-dlc\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Downloadable Content (DLC)\" \/>\n<meta property=\"og:description\" content=\"Zus\u00e4tzlicher Inhalt f\u00fcr ein Videospiel, der \u00fcber ein digitales Liefersystem erworben wird.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.aimcontrollers.com\/de\/lexikon\/downloadable-content-dlc\/\" \/>\n<meta property=\"og:site_name\" content=\"Aimcontrollers\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/aimcontrollers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AimControllerss\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/lexikon\\\/downloadable-content-dlc\\\/\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/lexikon\\\/downloadable-content-dlc\\\/\",\"name\":\"Downloadable Content (DLC) - Aimcontrollers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#website\"},\"datePublished\":\"2023-11-08T21:05:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/lexikon\\\/downloadable-content-dlc\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/lexikon\\\/downloadable-content-dlc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/lexikon\\\/downloadable-content-dlc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Downloadable Content (DLC)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/\",\"name\":\"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC\",\"description\":\"Eine der gr\u00f6\u00dften Marken, die vollst\u00e4ndig anpassbare und originelle Controller anbietet.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#organization\",\"name\":\"Aimcontrollers\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Aimcontrollers\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/aimcontrollers\",\"https:\\\/\\\/x.com\\\/AimControllerss\",\"https:\\\/\\\/instagram.com\\\/aimcontrollers\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aimcontrollerspl\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Downloadable Content (DLC) - Aimcontrollers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.aimcontrollers.com\/de\/lexikon\/downloadable-content-dlc\/","og_locale":"de_DE","og_type":"article","og_title":"Downloadable Content (DLC)","og_description":"Zus\u00e4tzlicher Inhalt f\u00fcr ein Videospiel, der \u00fcber ein digitales Liefersystem erworben wird.","og_url":"https:\/\/eu.aimcontrollers.com\/de\/lexikon\/downloadable-content-dlc\/","og_site_name":"Aimcontrollers","article_publisher":"http:\/\/www.facebook.com\/aimcontrollers","twitter_card":"summary_large_image","twitter_site":"@AimControllerss","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu.aimcontrollers.com\/de\/lexikon\/downloadable-content-dlc\/","url":"https:\/\/eu.aimcontrollers.com\/de\/lexikon\/downloadable-content-dlc\/","name":"Downloadable Content (DLC) - Aimcontrollers","isPartOf":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/#website"},"datePublished":"2023-11-08T21:05:34+00:00","breadcrumb":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/lexikon\/downloadable-content-dlc\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.aimcontrollers.com\/de\/lexikon\/downloadable-content-dlc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eu.aimcontrollers.com\/de\/lexikon\/downloadable-content-dlc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eu.aimcontrollers.com\/de\/"},{"@type":"ListItem","position":2,"name":"Downloadable Content (DLC)"}]},{"@type":"WebSite","@id":"https:\/\/eu.aimcontrollers.com\/de\/#website","url":"https:\/\/eu.aimcontrollers.com\/de\/","name":"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC","description":"Eine der gr\u00f6\u00dften Marken, die vollst\u00e4ndig anpassbare und originelle Controller anbietet.","publisher":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.aimcontrollers.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/eu.aimcontrollers.com\/de\/#organization","name":"Aimcontrollers","url":"https:\/\/eu.aimcontrollers.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/eu.aimcontrollers.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Aimcontrollers"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/aimcontrollers","https:\/\/x.com\/AimControllerss","https:\/\/instagram.com\/aimcontrollers\/","https:\/\/www.youtube.com\/user\/aimcontrollerspl\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/dictionary\/1321447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/dictionary"}],"about":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/types\/dictionary"}],"wp:attachment":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/media?parent=1321447"}],"wp:term":[{"taxonomy":"misspellings","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/misspellings?post=1321447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}