{"id":1004310,"date":"2019-11-24T13:44:36","date_gmt":"2019-11-24T12:44:36","guid":{"rendered":"https:\/\/testdo.aimcontrollers.com\/product\/red-alu-aim-micro-usb-cable\/"},"modified":"2022-03-07T14:27:48","modified_gmt":"2022-03-07T13:27:48","slug":"red-alu-aim-micro-usb-cable","status":"publish","type":"product","link":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/","title":{"rendered":"Rot Alu AiM Micro USB Cable"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul>\n<li>Rot Alu AiM Micro USB Cable<\/li>\n<li>L\u00e4nge: 3m<\/li>\n<li>Micro USB<\/li>\n<li>F\u00fcr PS4 Controllers<\/li>\n<\/ul>\n","protected":false},"featured_media":1214105,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[1173],"product_tag":[178,189,188],"misspellings":[],"class_list":{"0":"post-1004310","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zubehor","7":"product_tag-kabel","8":"product_tag-ps4-de","9":"product_tag-xbox-de","11":"first","12":"outofstock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rot Alu AiM Micro USB Cable - Aimcontrollers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rot Alu AiM Micro USB Cable\" \/>\n<meta property=\"og:description\" content=\"Rot Alu AiM Micro USB Cable  L\u00e4nge: 3m  Micro USB  F\u00fcr PS4 Controllers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/\" \/>\n<meta property=\"og:site_name\" content=\"Aimcontrollers\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/aimcontrollers\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-07T13:27:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/usb_micro_red.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AimControllerss\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/red-alu-aim-micro-usb-cable\\\/\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/red-alu-aim-micro-usb-cable\\\/\",\"name\":\"Rot Alu AiM Micro USB Cable - Aimcontrollers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/red-alu-aim-micro-usb-cable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/red-alu-aim-micro-usb-cable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/usb_micro_red.jpg\",\"datePublished\":\"2019-11-24T12:44:36+00:00\",\"dateModified\":\"2022-03-07T13:27:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/red-alu-aim-micro-usb-cable\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/red-alu-aim-micro-usb-cable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/red-alu-aim-micro-usb-cable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/usb_micro_red.jpg\",\"contentUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/usb_micro_red.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/red-alu-aim-micro-usb-cable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rot Alu AiM Micro USB Cable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/\",\"name\":\"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC\",\"description\":\"Eine der gr\u00f6\u00dften Marken, die vollst\u00e4ndig anpassbare und originelle Controller anbietet.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#organization\",\"name\":\"Aimcontrollers\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Aimcontrollers\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/aimcontrollers\",\"https:\\\/\\\/x.com\\\/AimControllerss\",\"https:\\\/\\\/instagram.com\\\/aimcontrollers\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aimcontrollerspl\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rot Alu AiM Micro USB Cable - Aimcontrollers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/","og_locale":"de_DE","og_type":"article","og_title":"Rot Alu AiM Micro USB Cable","og_description":"Rot Alu AiM Micro USB Cable  L\u00e4nge: 3m  Micro USB  F\u00fcr PS4 Controllers","og_url":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/","og_site_name":"Aimcontrollers","article_publisher":"http:\/\/www.facebook.com\/aimcontrollers","article_modified_time":"2022-03-07T13:27:48+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/usb_micro_red.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AimControllerss","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/","url":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/","name":"Rot Alu AiM Micro USB Cable - Aimcontrollers","isPartOf":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/#primaryimage"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/usb_micro_red.jpg","datePublished":"2019-11-24T12:44:36+00:00","dateModified":"2022-03-07T13:27:48+00:00","breadcrumb":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/#primaryimage","url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/usb_micro_red.jpg","contentUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/usb_micro_red.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/red-alu-aim-micro-usb-cable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eu.aimcontrollers.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/eu.aimcontrollers.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Rot Alu AiM Micro USB Cable"}]},{"@type":"WebSite","@id":"https:\/\/eu.aimcontrollers.com\/de\/#website","url":"https:\/\/eu.aimcontrollers.com\/de\/","name":"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC","description":"Eine der gr\u00f6\u00dften Marken, die vollst\u00e4ndig anpassbare und originelle Controller anbietet.","publisher":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.aimcontrollers.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/eu.aimcontrollers.com\/de\/#organization","name":"Aimcontrollers","url":"https:\/\/eu.aimcontrollers.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/eu.aimcontrollers.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Aimcontrollers"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/aimcontrollers","https:\/\/x.com\/AimControllerss","https:\/\/instagram.com\/aimcontrollers\/","https:\/\/www.youtube.com\/user\/aimcontrollerspl\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/product\/1004310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/media\/1214105"}],"wp:attachment":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/media?parent=1004310"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/product_brand?post=1004310"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/product_cat?post=1004310"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/product_tag?post=1004310"},{"taxonomy":"misspellings","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/misspellings?post=1004310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}