{"id":1445633,"date":"2026-06-23T17:36:06","date_gmt":"2026-06-23T15:36:06","guid":{"rendered":"https:\/\/eu.aimcontrollers.com\/product\/saxzu-aim-pc-mh5-controller\/"},"modified":"2026-06-25T20:54:26","modified_gmt":"2026-06-25T18:54:26","slug":"saxzu-aim-pc-mh5-controller","status":"publish","type":"product","link":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/","title":{"rendered":"SAXZU AIM PC MH5 Controller"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Der SAXZU Controller schl\u00e4gt anders.<br \/>\nMit seinen scharfen rot-schwarzen Streifen auf einer knackigen wei\u00dfen Basis ist er f\u00fcr Spieler gemacht, die in den entscheidenden Momenten erfolgreich sind.<br \/>\nSein Markenzeichen LuvF ist nicht nur auf die H\u00fclle gepr\u00e4gt, es ist die furchtlose Energie, die er in jeden Kampf tr\u00e4gt.<br \/>\nBleib eisig. Bleib verschlossen. Lass keine Lobby stehen.<\/p>\n","protected":false},"featured_media":1404021,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[5442],"product_tag":[5436,5449],"misspellings":[],"class_list":{"0":"post-1445633","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pc-controllers-de","7":"product_tag-de-pc-controller","8":"product_tag-pcpartners-de","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-variable","16":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SAXZU AIM PC MH5 Controller - Aimcontrollers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SAXZU AIM PC MH5 Controller\" \/>\n<meta property=\"og:description\" content=\"Der SAXZU Controller schl\u00e4gt anders. Mit seinen scharfen rot-schwarzen Streifen auf einer knackigen wei\u00dfen Basis ist er f\u00fcr Spieler gemacht, die in den entscheidenden Momenten erfolgreich sind. Sein Markenzeichen LuvF ist nicht nur auf die H\u00fclle gepr\u00e4gt, es ist die furchtlose Energie, die er in jeden Kampf tr\u00e4gt. Bleib eisig. Bleib verschlossen. Lass keine Lobby stehen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/\" \/>\n<meta property=\"og:site_name\" content=\"Aimcontrollers\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/aimcontrollers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T18:54:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2025\/08\/PRO_4_SAXZU_-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AimControllerss\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/saxzu-aim-pc-mh5-controller\\\/\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/saxzu-aim-pc-mh5-controller\\\/\",\"name\":\"SAXZU AIM PC MH5 Controller - Aimcontrollers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/saxzu-aim-pc-mh5-controller\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/saxzu-aim-pc-mh5-controller\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PRO_4_SAXZU_-1.png\",\"datePublished\":\"2026-06-23T15:36:06+00:00\",\"dateModified\":\"2026-06-25T18:54:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/saxzu-aim-pc-mh5-controller\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/saxzu-aim-pc-mh5-controller\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/saxzu-aim-pc-mh5-controller\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PRO_4_SAXZU_-1.png\",\"contentUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PRO_4_SAXZU_-1.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/produkt\\\/saxzu-aim-pc-mh5-controller\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SAXZU AIM PC MH5 Controller\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/\",\"name\":\"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC\",\"description\":\"Eine der gr\u00f6\u00dften Marken, die vollst\u00e4ndig anpassbare und originelle Controller anbietet.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#organization\",\"name\":\"Aimcontrollers\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Aimcontrollers\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/aimcontrollers\",\"https:\\\/\\\/x.com\\\/AimControllerss\",\"https:\\\/\\\/instagram.com\\\/aimcontrollers\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aimcontrollerspl\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SAXZU AIM PC MH5 Controller - Aimcontrollers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/","og_locale":"de_DE","og_type":"article","og_title":"SAXZU AIM PC MH5 Controller","og_description":"Der SAXZU Controller schl\u00e4gt anders. Mit seinen scharfen rot-schwarzen Streifen auf einer knackigen wei\u00dfen Basis ist er f\u00fcr Spieler gemacht, die in den entscheidenden Momenten erfolgreich sind. Sein Markenzeichen LuvF ist nicht nur auf die H\u00fclle gepr\u00e4gt, es ist die furchtlose Energie, die er in jeden Kampf tr\u00e4gt. Bleib eisig. Bleib verschlossen. Lass keine Lobby stehen.","og_url":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/","og_site_name":"Aimcontrollers","article_publisher":"http:\/\/www.facebook.com\/aimcontrollers","article_modified_time":"2026-06-25T18:54:26+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2025\/08\/PRO_4_SAXZU_-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@AimControllerss","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/","url":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/","name":"SAXZU AIM PC MH5 Controller - Aimcontrollers","isPartOf":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/#primaryimage"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2025\/08\/PRO_4_SAXZU_-1.png","datePublished":"2026-06-23T15:36:06+00:00","dateModified":"2026-06-25T18:54:26+00:00","breadcrumb":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/#primaryimage","url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2025\/08\/PRO_4_SAXZU_-1.png","contentUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2025\/08\/PRO_4_SAXZU_-1.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/eu.aimcontrollers.com\/de\/produkt\/saxzu-aim-pc-mh5-controller\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eu.aimcontrollers.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/eu.aimcontrollers.com\/shop\/"},{"@type":"ListItem","position":3,"name":"SAXZU AIM PC MH5 Controller"}]},{"@type":"WebSite","@id":"https:\/\/eu.aimcontrollers.com\/de\/#website","url":"https:\/\/eu.aimcontrollers.com\/de\/","name":"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC","description":"Eine der gr\u00f6\u00dften Marken, die vollst\u00e4ndig anpassbare und originelle Controller anbietet.","publisher":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.aimcontrollers.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/eu.aimcontrollers.com\/de\/#organization","name":"Aimcontrollers","url":"https:\/\/eu.aimcontrollers.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/eu.aimcontrollers.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Aimcontrollers"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/aimcontrollers","https:\/\/x.com\/AimControllerss","https:\/\/instagram.com\/aimcontrollers\/","https:\/\/www.youtube.com\/user\/aimcontrollerspl\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/product\/1445633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/media\/1404021"}],"wp:attachment":[{"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/media?parent=1445633"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/product_brand?post=1445633"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/product_cat?post=1445633"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/product_tag?post=1445633"},{"taxonomy":"misspellings","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/de\/wp-json\/wp\/v2\/misspellings?post=1445633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}