{"id":1395022,"date":"2025-05-27T19:53:06","date_gmt":"2025-05-27T17:53:06","guid":{"rendered":"https:\/\/eu.aimcontrollers.com\/product\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/"},"modified":"2025-12-10T18:52:11","modified_gmt":"2025-12-10T17:52:11","slug":"mando-xbox-series-x-ender-xbox-controller-aimcontrollers","status":"publish","type":"product","link":"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/","title":{"rendered":"Mando Xbox Series X ENDER &#8211; Xbox Controller &#8211; AimControllers"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Canaliza el misterio del Fin con este dise\u00f1o elegante y oscuro. Con penetrantes ojos morados y un aspecto sigiloso, est\u00e1 hecho para los jugadores que atacan desde las sombras.<\/p>\n","protected":false},"featured_media":1394967,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[1182],"product_tag":[192,4956,5405],"misspellings":[],"class_list":{"0":"post-1395022","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-xbox-one-controllers-es","7":"product_tag-xbox-es","8":"product_tag-xbox-controller-es","9":"product_tag-xboxmetalicline-es","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable","17":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mando Xbox Series X ENDER - Xbox Controller - AimControllers - Aimcontrollers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mando Xbox Series X ENDER - Xbox Controller - AimControllers\" \/>\n<meta property=\"og:description\" content=\"Canaliza el misterio del Fin con este dise\u00f1o elegante y oscuro. Con penetrantes ojos morados y un aspecto sigiloso, est\u00e1 hecho para los jugadores que atacan desde las sombras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/\" \/>\n<meta property=\"og:site_name\" content=\"Aimcontrollers\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/aimcontrollers\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T17:52:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2025\/05\/XBOX_PREDESIGN_PRO_DOUBLE__ENDER.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AimControllerss\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/producto\\\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\\\/\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/producto\\\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\\\/\",\"name\":\"Mando Xbox Series X ENDER - Xbox Controller - AimControllers - Aimcontrollers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/producto\\\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/producto\\\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/XBOX_PREDESIGN_PRO_DOUBLE__ENDER.png\",\"datePublished\":\"2025-05-27T17:53:06+00:00\",\"dateModified\":\"2025-12-10T17:52:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/producto\\\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/producto\\\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/producto\\\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/XBOX_PREDESIGN_PRO_DOUBLE__ENDER.png\",\"contentUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/XBOX_PREDESIGN_PRO_DOUBLE__ENDER.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/producto\\\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mando Xbox Series X ENDER &#8211; Xbox Controller &#8211; AimControllers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/\",\"name\":\"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC\",\"description\":\"Una de las marcas m\u00e1s importantes que ofrece controladores originales y totalmente personalizables.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/#organization\",\"name\":\"Aimcontrollers\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Aimcontrollers\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/aimcontrollers\",\"https:\\\/\\\/x.com\\\/AimControllerss\",\"https:\\\/\\\/instagram.com\\\/aimcontrollers\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aimcontrollerspl\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mando Xbox Series X ENDER - Xbox Controller - AimControllers - Aimcontrollers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/","og_locale":"es_ES","og_type":"article","og_title":"Mando Xbox Series X ENDER - Xbox Controller - AimControllers","og_description":"Canaliza el misterio del Fin con este dise\u00f1o elegante y oscuro. Con penetrantes ojos morados y un aspecto sigiloso, est\u00e1 hecho para los jugadores que atacan desde las sombras.","og_url":"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/","og_site_name":"Aimcontrollers","article_publisher":"http:\/\/www.facebook.com\/aimcontrollers","article_modified_time":"2025-12-10T17:52:11+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2025\/05\/XBOX_PREDESIGN_PRO_DOUBLE__ENDER.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@AimControllerss","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/","url":"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/","name":"Mando Xbox Series X ENDER - Xbox Controller - AimControllers - Aimcontrollers","isPartOf":{"@id":"https:\/\/eu.aimcontrollers.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/#primaryimage"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2025\/05\/XBOX_PREDESIGN_PRO_DOUBLE__ENDER.png","datePublished":"2025-05-27T17:53:06+00:00","dateModified":"2025-12-10T17:52:11+00:00","breadcrumb":{"@id":"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/#primaryimage","url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2025\/05\/XBOX_PREDESIGN_PRO_DOUBLE__ENDER.png","contentUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2025\/05\/XBOX_PREDESIGN_PRO_DOUBLE__ENDER.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/eu.aimcontrollers.com\/es\/producto\/mando-xbox-series-x-ender-xbox-controller-aimcontrollers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eu.aimcontrollers.com\/es\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/eu.aimcontrollers.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Mando Xbox Series X ENDER &#8211; Xbox Controller &#8211; AimControllers"}]},{"@type":"WebSite","@id":"https:\/\/eu.aimcontrollers.com\/es\/#website","url":"https:\/\/eu.aimcontrollers.com\/es\/","name":"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC","description":"Una de las marcas m\u00e1s importantes que ofrece controladores originales y totalmente personalizables.","publisher":{"@id":"https:\/\/eu.aimcontrollers.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.aimcontrollers.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eu.aimcontrollers.com\/es\/#organization","name":"Aimcontrollers","url":"https:\/\/eu.aimcontrollers.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eu.aimcontrollers.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Aimcontrollers"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/aimcontrollers","https:\/\/x.com\/AimControllerss","https:\/\/instagram.com\/aimcontrollers\/","https:\/\/www.youtube.com\/user\/aimcontrollerspl\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/eu.aimcontrollers.com\/es\/wp-json\/wp\/v2\/product\/1395022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.aimcontrollers.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eu.aimcontrollers.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/es\/wp-json\/wp\/v2\/media\/1394967"}],"wp:attachment":[{"href":"https:\/\/eu.aimcontrollers.com\/es\/wp-json\/wp\/v2\/media?parent=1395022"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/es\/wp-json\/wp\/v2\/product_brand?post=1395022"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/es\/wp-json\/wp\/v2\/product_cat?post=1395022"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/es\/wp-json\/wp\/v2\/product_tag?post=1395022"},{"taxonomy":"misspellings","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/es\/wp-json\/wp\/v2\/misspellings?post=1395022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}