{"id":1274508,"date":"2020-05-12T09:44:08","date_gmt":"2020-05-12T07:44:08","guid":{"rendered":"https:\/\/eu.aimcontrollers.com\/product\/manette-aim-chameleon-ps4\/"},"modified":"2025-02-04T13:57:36","modified_gmt":"2025-02-04T12:57:36","slug":"manette-aim-chameleon-ps4","status":"publish","type":"product","link":"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/","title":{"rendered":"Manette Aim Chameleon PS4"},"content":{"rendered":"\n\t<section class=\"section pbg\" id=\"section_1954982091\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-collapse row-full-width align-middle\"  id=\"row-1149145288\">\n\n\t<div id=\"col-1146007721\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h2>Aim Chameleon PS4 CONTROLLER<\/h2>\n<p>An original pad distinguished by an unusual chameleon theme, that changes colors at the right angle. The unique design goes hand in hand with perfect workmanship and durability, guaranteeing the reliable functioning of the device.<br \/>Each player wants the controller to work at his discretion and this is what the manufacturer provides, thanks to the possibility of adding programmable paddles, which can be adjust freely according to your personal preferences.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1146007721 > .col-inner {\n  padding: 10% 10% 10% 10%;\n  max-width: 520px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-626036614\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_988936370\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-800x800.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-768x768.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon.png 1000w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_988936370 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1954982091 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(244, 244, 244);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1380990849\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-center\"  id=\"row-1683844263\">\n\n\t<div id=\"col-62632828\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:40px;margin-bottom:40px;max-width:100%;height:1px;\"><\/div>\n<h2>Official Playstation 4 Controller Customised by AimControllers<\/h2>\n<p>All our custom controllers are genuine brand new Sony Playstation 4 Dualshock 4 V2 (Latest Version). After customisation process each controller is rigorously tested so quality is guaranteed.<\/p>\n<ul>\n<li style=\"display: inline-block;\"><img decoding=\"async\" src=\"\/wp-content\/themes\/flatsome-child\/img\/ikony\/check-black.svg\" width=\"22px\" height=\"22px\" \/> Lifetime warranty<\/li>\n<li style=\"display: inline-block;\"><img decoding=\"async\" src=\"\/wp-content\/themes\/flatsome-child\/img\/ikony\/check-black.svg\" width=\"22px\" height=\"22px\" \/> Designed and manufactured in Europe<\/li>\n<li style=\"display: inline-block;\"><img decoding=\"async\" src=\"\/wp-content\/themes\/flatsome-child\/img\/ikony\/check-black.svg\" width=\"22px\" height=\"22px\" \/> Compatible with PS4 and PC<\/li>\n<li style=\"display: inline-block;\"><img decoding=\"async\" src=\"\/wp-content\/themes\/flatsome-child\/img\/ikony\/check-black.svg\" width=\"22px\" height=\"22px\" \/> Fully customizable<\/li>\n<\/ul>\n<div class=\"is-divider divider clearfix\" style=\"margin-top:40px;margin-bottom:40px;max-width:100%;height:1px;\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1380990849 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1808032020\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-center\"  id=\"row-1310754927\">\n\n\t<div id=\"col-1781926133\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-1527896795\">\n\n\t<div id=\"col-605453564\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-369092420\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-369092420 {\n  padding-top: 0px;\n}\n<\/style>\n\t<\/div>\n\t\n<h2><span style=\"font-size: 140%;\">Modify<\/span><\/h2>\n<p>Customize your controller design to match your style. Please note: colors and designs may have slight differences due to the production process.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-605453564 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -37px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-center\"  id=\"row-860473039\">\n\n\t<div id=\"col-1051505671\" class=\"col medium-3 small-10 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 190px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Smart-Triggers-and-Bumpers-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Smart-Triggers-and-Bumpers-400x400.jpg 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Smart-Triggers-and-Bumpers-500x500.jpg 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Smart-Triggers-and-Bumpers-100x100.jpg 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Smart-Triggers-and-Bumpers-800x800.jpg 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Smart-Triggers-and-Bumpers-280x280.jpg 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Smart-Triggers-and-Bumpers-768x768.jpg 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Smart-Triggers-and-Bumpers.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-677992900\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-677992900 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n<h3 style=\"text-align: center;\"><span style=\"font-size: 100%;\">Smart Triggers \/ Smart Bumpers<\/span><\/h3>\n<p style=\"text-align: center;\">Smart triggers and bumpers will allow you to act faster \u2013 their response time is much quicker thanks to the digital mechanism.<\/p>\n\t<div id=\"gap-1727874876\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1727874876 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 190px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-grip-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-grip-400x400.jpg 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-grip-500x500.jpg 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-grip-100x100.jpg 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-grip-800x800.jpg 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-grip-280x280.jpg 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-grip-768x768.jpg 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-grip.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-624986204\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-624986204 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n<h3 style=\"text-align: center;\"><span style=\"font-size: 100%;\">Aim Grip<\/span><\/h3>\n<p style=\"text-align: center;\">Special rubbered texture makes your grip more comfortable and reliable that the AimController will not fall out of your hands.<\/p>\n\t<div id=\"gap-932563764\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-932563764 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1421625013\" class=\"col under-controller medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-1269619479\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1269619479 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1950800918\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-800x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-800x800.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon-768x768.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon.png 1000w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1950800918 {\n  width: 84%;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/eu.aimcontrollers.com\/fr\/configurateur-de-manette-ps4\/?component-5dd3e21cf3d40=option-5dd3ed1058180\" class=\"button white vpc-configure-button button\"  >\n\t\t<span>Customize Controller<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t \n\t<div id=\"col-1534195581\" class=\"col medium-3 small-10 large-3 small-col-first\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 190px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Paddles-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Paddles-400x400.jpg 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Paddles-500x500.jpg 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Paddles-100x100.jpg 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Paddles-800x800.jpg 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Paddles-280x280.jpg 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Paddles-768x768.jpg 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Paddles.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-1937315770\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1937315770 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n<h3 style=\"text-align: center;\"><span style=\"font-size: 100%;\">Paddles<\/span><\/h3>\n<p style=\"text-align: center;\">The paddles installed at the back of the controller improve the comfort and efficiency of playing.<\/p>\n\t<div id=\"gap-253218666\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-253218666 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 190px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-sticks-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-sticks-400x400.jpg 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-sticks-500x500.jpg 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-sticks-100x100.jpg 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-sticks-800x800.jpg 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-sticks-280x280.jpg 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-sticks-768x768.jpg 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/Aim-sticks.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-1592977063\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1592977063 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n<h3 style=\"text-align: center;\"><span style=\"font-size: 100%;\">Aim sticks<\/span><\/h3>\n<p style=\"text-align: center;\">Now you cannot only change their color, but even the height (small, medium and high).<\/p>\n\t<div id=\"gap-485075613\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-485075613 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1808032020 {\n  padding-top: 15px;\n  padding-bottom: 15px;\n}\n@media (min-width:550px) {\n  #section_1808032020 {\n    padding-top: 50px;\n    padding-bottom: 50px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-1227411120\">\n\n\t<div id=\"col-342642638\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:rgb(30, 30, 30);\" >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse align-middle\"  id=\"row-1649404963\">\n\n\t<div id=\"col-834496014\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 style=\"font-size: 200%;\">What&#8217;s inside the box<\/h2>\n<p>See what you get in your package<\/p>\n<ul>\n<li>Original Customized PS4 AimController (with LIFETIME WARRANTY)<\/li>\n<li>AimControllers Microfibre cloth<\/li>\n<li>AimControllers Flyers<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-78067833\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1553054263\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"709\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/04\/whatisinsidethebox-1151x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/04\/whatisinsidethebox-1151x800.png 1151w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/04\/whatisinsidethebox-500x347.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/04\/whatisinsidethebox-800x556.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/04\/whatisinsidethebox-576x400.png 576w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/04\/whatisinsidethebox-768x534.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/04\/whatisinsidethebox-1536x1067.png 1536w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/04\/whatisinsidethebox.png 1920w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1553054263 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1227411120 > .col > .col-inner {\n  padding: 40px 40px 40px 40px;\n}\n@media (min-width:550px) {\n  #row-1227411120 > .col > .col-inner {\n    padding: 50px 50px 50px 50px;\n  }\n}\n@media (min-width:850px) {\n  #row-1227411120 > .col > .col-inner {\n    padding: 20px 100px 20px 100px;\n  }\n}\n<\/style>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La manette originale qui met en valeur le motif inhabituel du cam\u00e9l\u00e9on.<\/p>\n","protected":false},"featured_media":1271597,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[5050],"product_tag":[5051],"misspellings":[],"class_list":["post-1274508","product","type-product","status-publish","has-post-thumbnail","product_cat-manettes-ps4","product_tag-ps4-controller-fr","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Manette Aim Chameleon PS4 - Aimcontrollers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manette Aim Chameleon PS4\" \/>\n<meta property=\"og:description\" content=\"La manette originale qui met en valeur le motif inhabituel du cam\u00e9l\u00e9on.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/\" \/>\n<meta property=\"og:site_name\" content=\"Aimcontrollers\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/aimcontrollers\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-04T12:57:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AimControllerss\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/produit\\\/manette-aim-chameleon-ps4\\\/\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/produit\\\/manette-aim-chameleon-ps4\\\/\",\"name\":\"Manette Aim Chameleon PS4 - Aimcontrollers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/produit\\\/manette-aim-chameleon-ps4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/produit\\\/manette-aim-chameleon-ps4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Aim_Hydro_Chameleon.png\",\"datePublished\":\"2020-05-12T07:44:08+00:00\",\"dateModified\":\"2025-02-04T12:57:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/produit\\\/manette-aim-chameleon-ps4\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/produit\\\/manette-aim-chameleon-ps4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/produit\\\/manette-aim-chameleon-ps4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Aim_Hydro_Chameleon.png\",\"contentUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Aim_Hydro_Chameleon.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/produit\\\/manette-aim-chameleon-ps4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Manette Aim Chameleon PS4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/\",\"name\":\"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC\",\"description\":\"Jedna z najwi\u0119kszych marek dostarczaj\u0105cych w pe\u0142ni modyfikowalne i oryginalne kontrolery.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/#organization\",\"name\":\"Aimcontrollers\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Aimcontrollers\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/aimcontrollers\",\"https:\\\/\\\/x.com\\\/AimControllerss\",\"https:\\\/\\\/instagram.com\\\/aimcontrollers\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aimcontrollerspl\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Manette Aim Chameleon PS4 - Aimcontrollers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/","og_locale":"fr_FR","og_type":"article","og_title":"Manette Aim Chameleon PS4","og_description":"La manette originale qui met en valeur le motif inhabituel du cam\u00e9l\u00e9on.","og_url":"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/","og_site_name":"Aimcontrollers","article_publisher":"http:\/\/www.facebook.com\/aimcontrollers","article_modified_time":"2025-02-04T12:57:36+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@AimControllerss","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/","url":"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/","name":"Manette Aim Chameleon PS4 - Aimcontrollers","isPartOf":{"@id":"https:\/\/eu.aimcontrollers.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/#primaryimage"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon.png","datePublished":"2020-05-12T07:44:08+00:00","dateModified":"2025-02-04T12:57:36+00:00","breadcrumb":{"@id":"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/#primaryimage","url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon.png","contentUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/05\/Aim_Hydro_Chameleon.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/eu.aimcontrollers.com\/fr\/produit\/manette-aim-chameleon-ps4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eu.aimcontrollers.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/eu.aimcontrollers.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Manette Aim Chameleon PS4"}]},{"@type":"WebSite","@id":"https:\/\/eu.aimcontrollers.com\/fr\/#website","url":"https:\/\/eu.aimcontrollers.com\/fr\/","name":"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC","description":"Jedna z najwi\u0119kszych marek dostarczaj\u0105cych w pe\u0142ni modyfikowalne i oryginalne kontrolery.","publisher":{"@id":"https:\/\/eu.aimcontrollers.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.aimcontrollers.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/eu.aimcontrollers.com\/fr\/#organization","name":"Aimcontrollers","url":"https:\/\/eu.aimcontrollers.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eu.aimcontrollers.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Aimcontrollers"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/aimcontrollers","https:\/\/x.com\/AimControllerss","https:\/\/instagram.com\/aimcontrollers\/","https:\/\/www.youtube.com\/user\/aimcontrollerspl\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/eu.aimcontrollers.com\/fr\/wp-json\/wp\/v2\/product\/1274508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.aimcontrollers.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eu.aimcontrollers.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/fr\/wp-json\/wp\/v2\/media\/1271597"}],"wp:attachment":[{"href":"https:\/\/eu.aimcontrollers.com\/fr\/wp-json\/wp\/v2\/media?parent=1274508"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/fr\/wp-json\/wp\/v2\/product_brand?post=1274508"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/fr\/wp-json\/wp\/v2\/product_cat?post=1274508"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/fr\/wp-json\/wp\/v2\/product_tag?post=1274508"},{"taxonomy":"misspellings","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/fr\/wp-json\/wp\/v2\/misspellings?post=1274508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}