{"id":1219862,"date":"2021-11-23T17:13:40","date_gmt":"2021-11-23T16:13:40","guid":{"rendered":"https:\/\/eu.aimcontrollers.com\/?page_id=1219862"},"modified":"2022-04-27T12:51:43","modified_gmt":"2022-04-27T10:51:43","slug":"rl9","status":"publish","type":"page","link":"https:\/\/eu.aimcontrollers.com\/pl\/rl9\/","title":{"rendered":"Aimcontrollers x RL9"},"content":{"rendered":"\t<div class=\"img has-hover hide-for-small x md-x lg-x y md-y lg-y\" id=\"image_1846562634\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_pc-1400x788.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_pc-1400x788.jpg 1400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_pc-500x281.jpg 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_pc-800x450.jpg 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_pc-711x400.jpg 711w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_pc-768x432.jpg 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_pc-1536x864.jpg 1536w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_pc.jpg 1919w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1846562634 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover show-for-small x md-x lg-x y md-y lg-y\" id=\"image_1704815162\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:160%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_mobile-450x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_mobile-450x800.jpg 450w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_mobile-500x889.jpg 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_mobile-800x1422.jpg 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_mobile-225x400.jpg 225w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_mobile-768x1365.jpg 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_mobile-864x1536.jpg 864w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_slider_lp_mobile.jpg 1080w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1704815162 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<section class=\"section dark has-mask mask-angled\" id=\"section_1849443466\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"314\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl_bg.png\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-large\"  id=\"row-1770626581\">\n\n\t<div id=\"col-1357397407\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-4083806307\" class=\"text\">\n\t\t\n<p class=\"p1\"><b>Graj jak najlepszy napastnik \u015bwiata!<\/b><\/p>\n\t\t\n<style>\n#text-4083806307 {\n  font-size: 1.75rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1460591726\" class=\"text\">\n\t\t\n<p><strong>#AIMHIGHER<\/strong><\/p>\n\t\t\n<style>\n#text-1460591726 {\n  font-size: 2.5rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3387801389\" class=\"text\">\n\t\t\n<p class=\"p2\">Limitowana edycja personalizowanych kontroler\u00f3w <strong>Roberta Lewandowskiego<\/strong> specjalnie<span class=\"Apple-converted-space\">\u00a0<\/span>dla Ciebie.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n\t\t\n<style>\n#text-3387801389 {\n  font-size: 1.4rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1357397407 > .col-inner {\n  margin: 30px 0px -15px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1770626581 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1849443466 {\n  padding-top: 100px;\n  padding-bottom: 100px;\n  background-color: rgb(200, 19, 38);\n}\n#section_1849443466 .section-bg img {\n  object-position: 33% 16%;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section dark has-mask mask-angled\" id=\"section_1576918508\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-297830486\">\n\n\t<div id=\"col-1018186786\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3906696256\" class=\"text\">\n\t\t\n<p class=\"lead\"><strong> Wsp\u00f3\u0142praca z Robertem Lewandowskim jest filarem projektu <span data-text-color=\"primary\">#AIMHIGHER<\/span> zainicjowanego przez mark\u0119 AIMCONTROLLERS, kt\u00f3ra skupia\u0107 b\u0119dzie gwiazdy \u015bwiatowego sportu. <\/strong><\/p>\n<p>Wsp\u00f3lnie z Robertem Lewandowskim chcemy zaproponowa\u0107 fanom futbolu na<br \/>\nca\u0142ym \u015bwiecie, wyj\u0105tkowy kontroler, kt\u00f3ry dostarczy niesamowitych<br \/>\nwra\u017ce\u0144 w czasie gry, jak r\u00f3wnie\u017c pozwoli im osi\u0105ga\u0107 lepsze wyniki<br \/>\npodczas rozgrywek e-sportowych. .<\/p>\n\t\t\n<style>\n#text-3906696256 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-780529807\">\n\n\t<div id=\"col-1413893872\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_869800209\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"462\" height=\"112\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9xaim.png\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_869800209 {\n  width: 45%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1576918508 {\n  padding-top: 70px;\n  padding-bottom: 70px;\n  background-color: rgb(0,0,0);\n}\n#section_1576918508 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.198);\n}\n@media (min-width:850px) {\n  #section_1576918508 {\n    padding-top: 100px;\n    padding-bottom: 100px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section dark\" id=\"section_635953156\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"575\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stripes-1.png\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1567673866\">\n\n\t<div id=\"col-1843078298\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1455956157\" class=\"text\">\n\t\t\n<p class=\"uppercase\" style=\"text-align: center;\"><strong>AIM X RL9 SERIA HIGHER<\/strong><\/p>\n\t\t\n<style>\n#text-1455956157 {\n  font-size: 2.25rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1843078298 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_635953156 {\n  padding-top: 104px;\n  padding-bottom: 104px;\n  background-color: rgb(200, 19, 38);\n}\n#section_635953156 .section-bg img {\n  object-position: 50% 48%;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section dark\" id=\"section_377668673\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:200%;\">AIM X RL9 PS5 HIGHER<\/span><b><\/b><\/h3><\/div>\n<div class=\"row row-small align-middle align-center row-dashed\"  id=\"row-445192205\">\n\n\t<div id=\"col-533886168\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-340861465\" >\n    <div class=\"slider slider-nav-simple slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": false,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_492871077\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:50px 50px 50px 50px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"510\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_pro_front_higher.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_pro_front_higher.png 726w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_pro_front_higher-500x351.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_pro_front_higher-569x400.png 569w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_492871077 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_380044086\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:50px 50px 50px 50px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"490\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/basic_back_ps5.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/basic_back_ps5.png 726w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/basic_back_ps5-500x337.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/basic_back_ps5-593x400.png 593w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_380044086 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-530193333\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p class=\"lead\">Limitowany kontroler do konsol Sony Play Station. Wyj\u0105tkowy gad\u017cet dla graczy i fan\u00f3w futbolu. Znakomicie sprawdzi w ka\u017cdym rodzaju gier.<\/p>\n<a href=\"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/kontroler-roberta-lewandowskiego-aim-x-rl9-ps5-higher\/\" target=\"_blank\" class=\"button primary is-larger\" rel=\"noopener\"  >\n\t\t<span>KUP TERAZ<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-307728012\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"text-align: center; font-size: 150%;\">Modyfikacje kontrolera AIM x RL9 PS5 HIGHER<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-445192205 > .col > .col-inner {\n  padding: 33px 0px 32px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"slider-wrapper relative\" id=\"slider-846003975\" style=\"background-color:rgb(17, 15, 16);\">\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": false,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n<div class=\"row align-middle align-center\"  id=\"row-1228843426\">\n\n\t<div id=\"col-1514051897\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-4137908792\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 150%; color: white;\">Wymienne AimSticks<\/h4>\n<p style=\"color: white;\">U\u017cywaj \u0142atwo wymiennych AimSticks i zapewnij sobie optymaln\u0105 swobod\u0119 ruch\u00f3w. Ni\u017csze gwarantuj\u0105 szybsz\u0105 reakcj\u0119 a wy\u017csze wi\u0119ksz\u0105 precyzj\u0119. Zmieniaj swoje AimStick dopasowuj\u0105c kontroler do Twoich ulubionych gier.<\/p>\n\t\t\n<style>\n#text-4137908792 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1514051897 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1514051897 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-167221179\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1848520414\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1848520414 {\n  width: 40%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-167221179 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-280402084\">\n\n\t<div id=\"col-777778510\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2705109002\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 150%; color: white;\">Aim Grip<\/h4>\n<p style=\"color: white;\">Gumowa, ergonomiczna, specjalna pow\u0142oka zwi\u0119ksza komfort gry podczas wielogodzinnych rozgrywek. Profilowane elementy korpusu i system non-slip polepszaj\u0105 kontrol\u0119 nad padem.<\/p>\n\t\t\n<style>\n#text-2705109002 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-777778510 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-777778510 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1050519216\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_312356976\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/higher-ps5-grip-no-paddles-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/higher-ps5-grip-no-paddles-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/higher-ps5-grip-no-paddles-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/higher-ps5-grip-no-paddles-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/higher-ps5-grip-no-paddles-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/higher-ps5-grip-no-paddles-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/higher-ps5-grip-no-paddles-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/higher-ps5-grip-no-paddles-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/higher-ps5-grip-no-paddles.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_312356976 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1050519216 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-885803514\">\n\n\t<div id=\"col-1247369732\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1075300058\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 150%; color: white;\">Do\u017cywotnia gwarancja<\/h4>\n<p style=\"color: white;\">Wybieraj\u0105c customowy kontroler AIM x RL9, otrzymujesz do\u017cywotni\u0105 gwarancj\u0119 na wszystkie modyfikacje.<\/p>\n\t\t\n<style>\n#text-1075300058 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1247369732 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1247369732 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1740939171\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1998284046\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1998284046 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1740939171 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:200%;\">AIM X RL9 XBOX HIGHER<\/span><b><\/b><\/h3><\/div>\n<div class=\"row row-small align-middle align-center row-dashed\"  id=\"row-1445366124\">\n\n\t<div id=\"col-1036609416\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-885737436\" >\n    <div class=\"slider slider-nav-simple slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": false,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_740501619\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:50px 50px 50px 50px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"510\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_xbox_smaller.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_xbox_smaller.png 726w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_xbox_smaller-500x351.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_xbox_smaller-569x400.png 569w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_740501619 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1108039278\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:50px 50px 50px 50px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"490\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/basic_xbox_back.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/basic_xbox_back.png 726w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/basic_xbox_back-500x337.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/basic_xbox_back-593x400.png 593w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1108039278 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2091429685\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p class=\"lead\">Limitowana edycja kontrolera do popularnej konsoli Xbox Series S. Dedykowana fanom Roberta Lewandowskiego i mi\u0142o\u015bnikom gier video.<\/p>\n<a href=\"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/kontroler-roberta-lewandowskiego-aim-x-rl9-xbox-higher\/\" target=\"_blank\" class=\"button primary is-larger\" rel=\"noopener\"  >\n\t\t<span>KUP TERAZ<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-509477368\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"text-align: center; font-size: 150%;\">Modyfikacje kontrolera AIM x RL9 XBOX HIGHER<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1445366124 > .col > .col-inner {\n  padding: 33px 0px 32px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"slider-wrapper relative\" id=\"slider-471355285\" style=\"background-color:rgb(17, 15, 16);\">\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": false,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n<div class=\"row align-middle align-center\"  id=\"row-742784842\">\n\n\t<div id=\"col-1025704250\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2310319372\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 150%; color: white;\">Wymienne AimSticks<\/h4>\n<p style=\"color: white;\">U\u017cywaj \u0142atwo wymiennych AimSticks i zapewnij sobie optymaln\u0105 swobod\u0119 ruch\u00f3w. Ni\u017csze gwarantuj\u0105 szybsz\u0105 reakcj\u0119 a wy\u017csze wi\u0119ksz\u0105 precyzj\u0119. Zmieniaj swoje AimStick dopasowuj\u0105c kontroler do Twoich ulubionych gier.<\/p>\n\t\t\n<style>\n#text-2310319372 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1025704250 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1025704250 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1112330414\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1318715517\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1318715517 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1112330414 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-554808433\">\n\n\t<div id=\"col-439761510\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1205162804\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 200%; color: white;\">Aim Grip<\/h4>\n<p style=\"color: white;\">Gumowa, ergonomiczna, specjalna pow\u0142oka zwi\u0119ksza komfort gry podczas wielogodzinnych rozgrywek. Profilowane elementy korpusu i system non-slip polepszaj\u0105 kontrol\u0119 nad padem.<\/p>\n\t\t\n<style>\n#text-1205162804 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-439761510 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-439761510 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-426671144\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_586424600\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-back-grip-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-back-grip-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-back-grip-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-back-grip-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-back-grip-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-back-grip-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-back-grip-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-back-grip-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-back-grip.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_586424600 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-426671144 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-802724010\">\n\n\t<div id=\"col-1708884803\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3901350576\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 150%; color: white;\">Do\u017cywotnia gwarancja<\/h4>\n<p style=\"color: white;\">Wybieraj\u0105c customowy kontroler AIM x RL9, otrzymujesz do\u017cywotni\u0105 gwarancj\u0119 na wszystkie modyfikacje.<\/p>\n\t\t\n<style>\n#text-3901350576 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1708884803 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1708884803 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-397302411\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1817159057\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1817159057 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-397302411 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_377668673 {\n  padding-top: 32px;\n  padding-bottom: 32px;\n  background-color: rgb(17, 15, 16);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section dark\" id=\"section_1642738137\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"575\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stripes-1.png\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-328604029\">\n\n\t<div id=\"col-1337486680\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3524429573\" class=\"text\">\n\t\t\n<p class=\"uppercase\" style=\"text-align: center;\"><strong>Zyskaj przewag\u0119 dzi\u0119ki serii <span style=\"color: black;\">HIGHER PRO<\/span><\/strong><\/p>\n\t\t\n<style>\n#text-3524429573 {\n  font-size: 2.25rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1337486680 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1642738137 {\n  padding-top: 104px;\n  padding-bottom: 104px;\n  background-color: rgb(200, 19, 38);\n}\n#section_1642738137 .section-bg img {\n  object-position: 61% 82%;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section dark\" id=\"section_1508207302\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:200%;\">AIM X RL9 PS5 HIGHER PRO<\/span><b><\/b><\/h3><\/div>\n<div class=\"row row-small align-middle align-center row-dashed\"  id=\"row-841661402\">\n\n\t<div id=\"col-901815729\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-1090072785\" >\n    <div class=\"slider slider-nav-simple slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": false,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1204562159\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:50px 50px 50px 50px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"510\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_pro_higher_rl9.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_pro_higher_rl9.png 726w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_pro_higher_rl9-500x351.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_pro_higher_rl9-569x400.png 569w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1204562159 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1775304723\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:50px 50px 50px 50px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"490\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/back_ps5_rl9_higher.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/back_ps5_rl9_higher.png 726w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/back_ps5_rl9_higher-500x337.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/back_ps5_rl9_higher-593x400.png 593w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1775304723 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-172545797\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p><span data-text-color=\"primary\">SERIA HIGHER PRO<\/span><\/p>\n<p class=\"lead\">Ciesz si\u0119 wszystkimi cechami kontrolera Higher i korzystaj z dodatkowych funkcji PRO.<\/p>\n<a href=\"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/kontroler-roberta-lewandowskiego-aim-x-rl9-ps5-higher-pro\/\" target=\"_blank\" class=\"button primary is-larger\" rel=\"noopener\"  >\n\t\t<span>KUP TERAZ<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1684543754\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"text-align: center; font-size: 150%;\">Modyfikacje kontrolera AIM x RL9 PS5 HIGHER <span data-text-color=\"primary\">PRO<\/span><\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-841661402 > .col > .col-inner {\n  padding: 33px 0px 32px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"slider-wrapper relative\" id=\"slider-1056082329\" style=\"background-color:rgb(17, 15, 16);\">\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": false,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n<div class=\"row align-middle align-center\"  id=\"row-921054740\">\n\n\t<div id=\"col-555486195\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3624405374\" class=\"text\">\n\t\t\n<p><span data-text-color=\"primary\">SERIA HIGHER PRO<\/span><\/p>\n<h4 style=\"font-size: 150%; color: white;\">Remapping Paddles<\/h4>\n<p style=\"color: white;\">Umieszczone w tylnej cz\u0119\u015bci kontrolera \u0142opatki zwi\u0119kszaj\u0105 komfort i efektywno\u015b\u0107 gry.<br \/>\nRemapping sprawia, \u017ce \u0142opatki s\u0105 programowalne i umo\u017cliwiaj\u0105 dowolne przypisanie funkcji przycisk\u00f3w znajduj\u0105cych si\u0119 na panelu przednim (X, O, tr\u00f3jk\u0105t, kwadrat, D-Pad, L3, R3, L1 &amp; R1). Zmieniaj funkcje \u0142opatek w zale\u017cno\u015bci od gry!<\/p>\n\t\t\n<style>\n#text-3624405374 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-555486195 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-555486195 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-442996316\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_763388225\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_763388225 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-442996316 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-1449232896\">\n\n\t<div id=\"col-1472458827\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-494638451\" class=\"text\">\n\t\t\n<p><span data-text-color=\"primary\">SERIA HIGHER PRO<\/span><\/p>\n<h4 style=\"font-size: 150%; color: white;\">Smart Triggers &amp; Smart Bumpers<\/h4>\n<p style=\"color: white;\">Cyfrowe mechanizmy skracaj\u0105 czas reakcji dzi\u0119ki czemu zdobywasz przewag\u0119 nad konkurencj\u0105. Musisz to poczu\u0107, kr\u00f3tki skok i charakterystyczne klikni\u0119cie odmieni\u0105 ka\u017cd\u0105 rozgrywk\u0119.<\/p>\n\t\t\n<style>\n#text-494638451 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1472458827 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1472458827 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1730899346\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1259178418\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-rl9-2-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-rl9-2-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-rl9-2-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-rl9-2-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-rl9-2-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-rl9-2-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-rl9-2-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-rl9-2-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-rl9-2.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1259178418 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1730899346 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-1012578255\">\n\n\t<div id=\"col-179588119\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-433189785\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 150%; color: white;\">Wymienne AimSticks<\/h4>\n<p style=\"color: white;\">U\u017cywaj \u0142atwo wymiennych AimSticks i zapewnij sobie optymaln\u0105 swobod\u0119 ruch\u00f3w. Ni\u017csze gwarantuj\u0105 szybsz\u0105 reakcj\u0119 a wy\u017csze wi\u0119ksz\u0105 precyzj\u0119. Zmieniaj swoje AimStick dopasowuj\u0105c kontroler do Twoich ulubionych gier.<\/p>\n\t\t\n<style>\n#text-433189785 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-179588119 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-179588119 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1039822096\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1234610892\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick_pro-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick_pro-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick_pro-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick_pro-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick_pro-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick_pro-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick_pro-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick_pro-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_stick_pro.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1234610892 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1039822096 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-1697528565\">\n\n\t<div id=\"col-540071646\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1322946950\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 150%; color: white;\">Aim Grip<\/h4>\n<p style=\"color: white;\">Gumowa, ergonomiczna, specjalna pow\u0142oka zwi\u0119ksza komfort gry podczas wielogodzinnych rozgrywek. Profilowane elementy korpusu i system non-slip polepszaj\u0105 kontrol\u0119 nad padem.<\/p>\n\t\t\n<style>\n#text-1322946950 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-540071646 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-540071646 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-339909347\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2119433799\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/ps5_higher_pro.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2119433799 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-339909347 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-1278714718\">\n\n\t<div id=\"col-567443713\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2226084682\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 150%; color: white;\">Do\u017cywotnia gwarancja<\/h4>\n<p style=\"color: white;\">Wybieraj\u0105c customowy kontroler AIM x RL9, otrzymujesz do\u017cywotni\u0105 gwarancj\u0119 na wszystkie modyfikacje.<\/p>\n\t\t\n<style>\n#text-2226084682 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-567443713 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-567443713 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-788358799\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_181900007\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/front-life-time.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_181900007 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-788358799 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:200%;\">AIM X RL9 XBOX HIGHER PRO<\/span><b><\/b><\/h3><\/div>\n<div class=\"row row-small align-middle align-center row-dashed\"  id=\"row-1211519467\">\n\n\t<div id=\"col-1963106062\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-253354550\" >\n    <div class=\"slider slider-nav-simple slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": false,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_826495210\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:50px 50px 50px 50px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"510\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_xbox_smaller.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_xbox_smaller.png 726w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_xbox_smaller-500x351.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9_xbox_smaller-569x400.png 569w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_826495210 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_561613690\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:50px 50px 50px 50px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"490\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/pro_xbox_back.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/pro_xbox_back.png 726w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/pro_xbox_back-500x337.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/pro_xbox_back-593x400.png 593w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_561613690 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2139622267\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p><span data-text-color=\"primary\">SERIA HIGHER PRO<\/span><\/p>\n<p class=\"lead\">Specjalnie dla PRO-graczy, limitowana wersja kontrolera do konsoli Xbox Series X\/S.<br \/>\nDodatkowe funkcje podnosz\u0105 jako\u015b\u0107 gry i poprawi\u0105 Twoje wyniki<\/p>\n<a href=\"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/kontroler-roberta-lewandowskiego-aim-x-rl9-xbox-higher-pro\/\" target=\"_blank\" class=\"button primary is-larger\" rel=\"noopener\"  >\n\t\t<span>KUP TERAZ<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-797985872\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"text-align: center; font-size: 150%;\">Modyfikacje kontrolera AIM x RL9 XBOX HIGHER <span data-text-color=\"primary\">PRO<\/span><\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1211519467 > .col > .col-inner {\n  padding: 33px 0px 32px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"slider-wrapper relative\" id=\"slider-1262797603\" style=\"background-color:rgb(17, 15, 16);\">\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": false,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n<div class=\"row align-middle align-center\"  id=\"row-88289150\">\n\n\t<div id=\"col-1202100835\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3984397182\" class=\"text\">\n\t\t\n<p><span data-text-color=\"primary\">SERIA HIGHER PRO<\/span><\/p>\n<h4 style=\"font-size: 150%; color: white;\">Spider Action Paddles<\/h4>\n<p style=\"color: white;\">Dodatkowe, umieszczone w tylnej cz\u0119\u015bci kontrolera \u0142opatki, zwi\u0119kszaj\u0105 komfort i skracaj\u0105 czas reakcji podczas gry. W wersji Xbox HIGHER PRO, ergonomiczne Spider Action v1 s\u0105 na sta\u0142e przypisane do specjalnie zaprogramowanej konfiguracji, dzi\u0119ki czemu szybciej wykonasz ka\u017cdy ruch, zyskuj\u0105c przewag\u0119 w grze.<\/p>\n\t\t\n<style>\n#text-3984397182 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1202100835 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1202100835 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1980046729\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1964358647\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1964358647 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1980046729 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-1467384007\">\n\n\t<div id=\"col-2119423374\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-690170063\" class=\"text\">\n\t\t\n<p><span data-text-color=\"primary\">SERIA HIGHER PRO<\/span><\/p>\n<h4 style=\"font-size: 150%; color: white;\">Smart Triggers<\/h4>\n<p style=\"color: white;\">Cyfrowe mechanizmy skracaj\u0105 czas reakcji dzi\u0119ki czemu zdobywasz przewag\u0119 nad konkurencj\u0105. Musisz to poczu\u0107, kr\u00f3tki skok i charakterystyczne klikni\u0119cie odmieni\u0105 ka\u017cd\u0105 rozgrywk\u0119<\/p>\n\t\t\n<style>\n#text-690170063 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2119423374 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2119423374 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-118719592\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1320130831\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-xbox-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-xbox-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-xbox-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-xbox-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-xbox-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-xbox-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-xbox-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-xbox-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/trigger-xbox.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1320130831 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-118719592 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-515563117\">\n\n\t<div id=\"col-2028833\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2733130651\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 150%; color: white;\">Wymienne AimSticks<\/h4>\n<p style=\"color: white;\">U\u017cywaj \u0142atwo wymiennych AimSticks i zapewnij sobie optymaln\u0105 swobod\u0119 ruch\u00f3w. Ni\u017csze gwarantuj\u0105 szybsz\u0105 reakcj\u0119 a wy\u017csze wi\u0119ksz\u0105 precyzj\u0119. Zmieniaj swoje AimStick dopasowuj\u0105c kontroler do Twoich ulubionych gier.<\/p>\n\t\t\n<style>\n#text-2733130651 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2028833 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2028833 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-780107171\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_472054405\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-paddles-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-paddles-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-paddles-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-paddles-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-paddles-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-paddles-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-paddles-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-paddles-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/stick-xbox-paddles.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_472054405 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-780107171 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-1805880957\">\n\n\t<div id=\"col-1274149552\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2765729245\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 150%; color: white;\">Aim Grip<\/h4>\n<p style=\"color: white;\">Gumowa, ergonomiczna, specjalna pow\u0142oka zwi\u0119ksza komfort gry podczas wielogodzinnych rozgrywek. Profilowane elementy korpusu i system non-slip polepszaj\u0105 kontrol\u0119 nad padem.<\/p>\n\t\t\n<style>\n#text-2765729245 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1274149552 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1274149552 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1063268524\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_675337867\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-paddles.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_675337867 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1063268524 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-2077644681\">\n\n\t<div id=\"col-1692417636\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-352801520\" class=\"text\">\n\t\t\n<h4 style=\"font-size: 150%; color: white;\">Do\u017cywotnia gwarancja<\/h4>\n<p style=\"color: white;\">Wybieraj\u0105c customowy kontroler AIM x RL9, otrzymujesz do\u017cywotni\u0105 gwarancj\u0119 na wszystkie modyfikacje.<\/p>\n\t\t\n<style>\n#text-352801520 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1692417636 > .col-inner {\n  margin: 32px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1692417636 > .col-inner {\n    margin: 32px 0px 32px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1581903530\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_867309360\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"800\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-799x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-799x800.png 799w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-500x500.png 500w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-100x100.png 100w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-800x801.png 800w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-400x400.png 400w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-280x280.png 280w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time-768x769.png 768w, https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/xbox-life-time.png 1079w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_867309360 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1581903530 > .col-inner {\n  margin: 32px 0px 32px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1508207302 {\n  padding-top: 32px;\n  padding-bottom: 32px;\n  background-color: rgb(17, 15, 16);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section dark\" id=\"section_1211527555\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-132140337\">\n\n\t<div id=\"col-314738320\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1161861245\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"40\" height=\"40\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/return.svg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1161861245 {\n  width: 20%;\n}\n<\/style>\n\t<\/div>\n\t\n<p><strong>Do\u017cywotnia gwarancja<\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1319161079\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_116156857\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"583\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/03\/quality-2.svg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_116156857 {\n  width: 20%;\n}\n<\/style>\n\t<\/div>\n\t\n<p><strong>Najwy\u017csza jako\u015b\u0107<\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1713062933\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_292170029\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"583\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/08\/proplayers.svg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_292170029 {\n  width: 20%;\n}\n<\/style>\n\t<\/div>\n\t\n<p><strong>Polecane przez profesjonalist\u00f3w<\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-885933551\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1567974448\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"40\" height=\"40\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2020\/03\/table.svg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1567974448 {\n  width: 20%;\n}\n<\/style>\n\t<\/div>\n\t\n<p><strong>Wyprodukowane w Europie<\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1211527555 {\n  padding-top: 32px;\n  padding-bottom: 32px;\n  background-color: rgb(200, 19, 38);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1740856139\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-638253192\">\n\n\t<div id=\"col-244293560\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:200%;\">Wszystkie produkty z serii aim x rl9<\/span><b><\/b><\/h3><\/div>\n\t\n  \n    <div id=\"product-grid-1895964973\" class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small has-shadow row-box-shadow-1 row-box-shadow-5-hover row-masonry\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  \n\t     <\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1740856139 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section dark\" id=\"section_750031976\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-center\"  id=\"row-1922998948\">\n\n\t<div id=\"col-1660288200\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1927374077\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"462\" height=\"112\" src=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2021\/11\/rl9xaim.png\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1927374077 {\n  width: 30%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2182352453\" class=\"text\">\n\t\t\n<p><strong>#AIMHIGHER<\/strong><\/p>\n\t\t\n<style>\n#text-2182352453 {\n  font-size: 2.5rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1660288200 > .col-inner {\n  margin: 0px 0px -62px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_750031976 {\n  padding-top: 62px;\n  padding-bottom: 62px;\n  background-color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"misspellings":[],"class_list":["post-1219862","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aimcontrollers x RL9 - Oficjalne Kontrolery Roberta Lewandowskiego<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.aimcontrollers.com\/pl\/rl9\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aimcontrollers x RL9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.aimcontrollers.com\/pl\/rl9\/\" \/>\n<meta property=\"og:site_name\" content=\"Aimcontrollers\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/aimcontrollers\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-27T10:51:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AimControllerss\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/rl9\\\/\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/rl9\\\/\",\"name\":\"Aimcontrollers x RL9 - Oficjalne Kontrolery Roberta Lewandowskiego\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#website\"},\"datePublished\":\"2021-11-23T16:13:40+00:00\",\"dateModified\":\"2022-04-27T10:51:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/rl9\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/rl9\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/rl9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aimcontrollers x RL9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/\",\"name\":\"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC\",\"description\":\"Jedna z najwi\u0119kszych marek dostarczaj\u0105cych w pe\u0142ni modyfikowalne i oryginalne kontrolery.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#organization\",\"name\":\"Aimcontrollers\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Aimcontrollers\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/aimcontrollers\",\"https:\\\/\\\/x.com\\\/AimControllerss\",\"https:\\\/\\\/instagram.com\\\/aimcontrollers\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aimcontrollerspl\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aimcontrollers x RL9 - Oficjalne Kontrolery Roberta Lewandowskiego","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.aimcontrollers.com\/pl\/rl9\/","og_locale":"pl_PL","og_type":"article","og_title":"Aimcontrollers x RL9","og_url":"https:\/\/eu.aimcontrollers.com\/pl\/rl9\/","og_site_name":"Aimcontrollers","article_publisher":"http:\/\/www.facebook.com\/aimcontrollers","article_modified_time":"2022-04-27T10:51:43+00:00","twitter_card":"summary_large_image","twitter_site":"@AimControllerss","twitter_misc":{"Szacowany czas czytania":"11 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu.aimcontrollers.com\/pl\/rl9\/","url":"https:\/\/eu.aimcontrollers.com\/pl\/rl9\/","name":"Aimcontrollers x RL9 - Oficjalne Kontrolery Roberta Lewandowskiego","isPartOf":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/#website"},"datePublished":"2021-11-23T16:13:40+00:00","dateModified":"2022-04-27T10:51:43+00:00","breadcrumb":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/rl9\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.aimcontrollers.com\/pl\/rl9\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eu.aimcontrollers.com\/pl\/rl9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eu.aimcontrollers.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Aimcontrollers x RL9"}]},{"@type":"WebSite","@id":"https:\/\/eu.aimcontrollers.com\/pl\/#website","url":"https:\/\/eu.aimcontrollers.com\/pl\/","name":"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC","description":"Jedna z najwi\u0119kszych marek dostarczaj\u0105cych w pe\u0142ni modyfikowalne i oryginalne kontrolery.","publisher":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.aimcontrollers.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/eu.aimcontrollers.com\/pl\/#organization","name":"Aimcontrollers","url":"https:\/\/eu.aimcontrollers.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/eu.aimcontrollers.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Aimcontrollers"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/aimcontrollers","https:\/\/x.com\/AimControllerss","https:\/\/instagram.com\/aimcontrollers\/","https:\/\/www.youtube.com\/user\/aimcontrollerspl\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/pages\/1219862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/comments?post=1219862"}],"version-history":[{"count":61,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/pages\/1219862\/revisions"}],"predecessor-version":[{"id":1254401,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/pages\/1219862\/revisions\/1254401"}],"wp:attachment":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/media?parent=1219862"}],"wp:term":[{"taxonomy":"misspellings","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/misspellings?post=1219862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}