{"id":1000581,"date":"2019-11-15T18:02:42","date_gmt":"2019-11-15T17:02:42","guid":{"rendered":"https:\/\/testdo.aimcontrollers.com\/product\/yellow-medium-ps4-aim-stick\/"},"modified":"2022-11-09T16:08:52","modified_gmt":"2022-11-09T15:08:52","slug":"yellow-medium-ps4-aim-stick","status":"publish","type":"product","link":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/","title":{"rendered":"\u017b\u00f3\u0142ty analog od PS o \u015bredniej wielko\u015bci"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul>\n<li style=\"font-weight: 400;\"><b>\u017b\u00f3\u0142ty analog od PS o \u015bredniej wielko\u015bci<\/b><span style=\"font-weight: 400;\"> pozwalaj\u0105cy na zachowanie maksymalnego komfortu grania i podejmowanie b\u0142yskawicznych decyzji<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Wymie\u0144 uszkodzone ga\u0142ki na zupe\u0142nie nowe i zachowaj estetyczny, oryginalny wygl\u0105d swojego pada<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Ponadprzeci\u0119tna jako\u015b\u0107 wykonania oraz mo\u017cliwo\u015b\u0107 wykorzystania w padach do PS, a tak\u017ce Xbox<\/span><\/li>\n<li style=\"font-weight: 400;\"><\/li>\n<\/ul>\n","protected":false},"featured_media":1000392,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[1167],"product_tag":[180,191,169,150],"misspellings":[],"class_list":{"0":"post-1000581","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-akcesoria","7":"product_tag-aim-stick-pl","8":"product_tag-ps4-pl","9":"product_tag-sredni","10":"product_tag-zolty","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u017b\u00f3\u0142ty analog od PS o \u015bredniej wielko\u015bci - Aimcontrollers<\/title>\n<meta name=\"description\" content=\"Najwy\u017csza mo\u017cliwa jako\u015b\u0107 analog\u00f3w oraz stuprocentowa kompatybilno\u015b\u0107 \u2013 nie tylko z padami do PS4, ale r\u00f3wnie\u017c Xbox One\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u017b\u00f3\u0142ty analog od PS o \u015bredniej wielko\u015bci\" \/>\n<meta property=\"og:description\" content=\"Najwy\u017csza mo\u017cliwa jako\u015b\u0107 analog\u00f3w oraz stuprocentowa kompatybilno\u015b\u0107 \u2013 nie tylko z padami do PS4, ale r\u00f3wnie\u017c Xbox One\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/\" \/>\n<meta property=\"og:site_name\" content=\"Aimcontrollers\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/aimcontrollers\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T15:08:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/ps4-yellow-medium.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AimControllerss\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/yellow-medium-ps4-aim-stick\\\/\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/yellow-medium-ps4-aim-stick\\\/\",\"name\":\"\u017b\u00f3\u0142ty analog od PS o \u015bredniej wielko\u015bci - Aimcontrollers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/yellow-medium-ps4-aim-stick\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/yellow-medium-ps4-aim-stick\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ps4-yellow-medium.jpg\",\"datePublished\":\"2019-11-15T17:02:42+00:00\",\"dateModified\":\"2022-11-09T15:08:52+00:00\",\"description\":\"Najwy\u017csza mo\u017cliwa jako\u015b\u0107 analog\u00f3w oraz stuprocentowa kompatybilno\u015b\u0107 \u2013 nie tylko z padami do PS4, ale r\u00f3wnie\u017c Xbox One\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/yellow-medium-ps4-aim-stick\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/yellow-medium-ps4-aim-stick\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/yellow-medium-ps4-aim-stick\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ps4-yellow-medium.jpg\",\"contentUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ps4-yellow-medium.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"ps4 yellow medium stick\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/yellow-medium-ps4-aim-stick\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u017b\u00f3\u0142ty analog od PS o \u015bredniej wielko\u015bci\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/\",\"name\":\"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC\",\"description\":\"Jedna z najwi\u0119kszych marek dostarczaj\u0105cych w pe\u0142ni modyfikowalne i oryginalne kontrolery.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#organization\",\"name\":\"Aimcontrollers\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Aimcontrollers\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/aimcontrollers\",\"https:\\\/\\\/x.com\\\/AimControllerss\",\"https:\\\/\\\/instagram.com\\\/aimcontrollers\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aimcontrollerspl\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u017b\u00f3\u0142ty analog od PS o \u015bredniej wielko\u015bci - Aimcontrollers","description":"Najwy\u017csza mo\u017cliwa jako\u015b\u0107 analog\u00f3w oraz stuprocentowa kompatybilno\u015b\u0107 \u2013 nie tylko z padami do PS4, ale r\u00f3wnie\u017c Xbox One","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/","og_locale":"pl_PL","og_type":"article","og_title":"\u017b\u00f3\u0142ty analog od PS o \u015bredniej wielko\u015bci","og_description":"Najwy\u017csza mo\u017cliwa jako\u015b\u0107 analog\u00f3w oraz stuprocentowa kompatybilno\u015b\u0107 \u2013 nie tylko z padami do PS4, ale r\u00f3wnie\u017c Xbox One","og_url":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/","og_site_name":"Aimcontrollers","article_publisher":"http:\/\/www.facebook.com\/aimcontrollers","article_modified_time":"2022-11-09T15:08:52+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/ps4-yellow-medium.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AimControllerss","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/","url":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/","name":"\u017b\u00f3\u0142ty analog od PS o \u015bredniej wielko\u015bci - Aimcontrollers","isPartOf":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/#primaryimage"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/ps4-yellow-medium.jpg","datePublished":"2019-11-15T17:02:42+00:00","dateModified":"2022-11-09T15:08:52+00:00","description":"Najwy\u017csza mo\u017cliwa jako\u015b\u0107 analog\u00f3w oraz stuprocentowa kompatybilno\u015b\u0107 \u2013 nie tylko z padami do PS4, ale r\u00f3wnie\u017c Xbox One","breadcrumb":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/#primaryimage","url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/ps4-yellow-medium.jpg","contentUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/ps4-yellow-medium.jpg","width":1000,"height":1000,"caption":"ps4 yellow medium stick"},{"@type":"BreadcrumbList","@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/yellow-medium-ps4-aim-stick\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eu.aimcontrollers.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/eu.aimcontrollers.com\/shop\/"},{"@type":"ListItem","position":3,"name":"\u017b\u00f3\u0142ty analog od PS o \u015bredniej wielko\u015bci"}]},{"@type":"WebSite","@id":"https:\/\/eu.aimcontrollers.com\/pl\/#website","url":"https:\/\/eu.aimcontrollers.com\/pl\/","name":"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC","description":"Jedna z najwi\u0119kszych marek dostarczaj\u0105cych w pe\u0142ni modyfikowalne i oryginalne kontrolery.","publisher":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.aimcontrollers.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/eu.aimcontrollers.com\/pl\/#organization","name":"Aimcontrollers","url":"https:\/\/eu.aimcontrollers.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/eu.aimcontrollers.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Aimcontrollers"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/aimcontrollers","https:\/\/x.com\/AimControllerss","https:\/\/instagram.com\/aimcontrollers\/","https:\/\/www.youtube.com\/user\/aimcontrollerspl\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/product\/1000581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/media\/1000392"}],"wp:attachment":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/media?parent=1000581"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/product_brand?post=1000581"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/product_cat?post=1000581"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/product_tag?post=1000581"},{"taxonomy":"misspellings","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/misspellings?post=1000581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}