{"id":1000614,"date":"2019-11-15T19:34:26","date_gmt":"2019-11-15T18:34:26","guid":{"rendered":"https:\/\/testdo.aimcontrollers.com\/product\/red-high-ps4-aim-stick\/"},"modified":"2022-11-09T16:08:51","modified_gmt":"2022-11-09T15:08:51","slug":"red-high-ps4-aim-stick","status":"publish","type":"product","link":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/","title":{"rendered":"Wysoki analog od PS w czerwonym kolorze"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul>\n<li style=\"font-weight: 400;\"><b>Wysoki analog od PS w czerwonym kolorze<\/b><span style=\"font-weight: 400;\">, dzi\u0119ki kt\u00f3remu celowanie jest precyzyjne jak nigdy dot\u0105d \u2013 rozwi\u0105zanie idealne do gier typu FPS<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Oryginalny wygl\u0105d urz\u0105dzenia, zachowany nawet w przypadku wymiany ga\u0142ek \u2013 jest to \u0142atwe i bezproblemowe dla ka\u017cdego gracza<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Najwy\u017csza jako\u015b\u0107 rekomendowana przez producenta oraz stuprocentowa kompatybilno\u015b\u0107 z ka\u017cdym padem do PS oraz Xbox<\/span><\/li>\n<\/ul>\n","protected":false},"featured_media":1000441,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[1167],"product_tag":[180,153,191,168],"misspellings":[],"class_list":{"0":"post-1000614","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-akcesoria","7":"product_tag-aim-stick-pl","8":"product_tag-czerwony","9":"product_tag-ps4-pl","10":"product_tag-wysoki","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wysoki analog od PS w czerwonym kolorze - Aimcontrollers<\/title>\n<meta name=\"description\" content=\"Du\u017ca wytrzyma\u0142o\u015b\u0107 ga\u0142ek, a w przypadku ich wytarcia, mo\u017cliwo\u015b\u0107 wymiany na nowe \u2013 r\u00f3wnie\u017c w innym kolorze lub rozmiarze\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wysoki analog od PS w czerwonym kolorze\" \/>\n<meta property=\"og:description\" content=\"Du\u017ca wytrzyma\u0142o\u015b\u0107 ga\u0142ek, a w przypadku ich wytarcia, mo\u017cliwo\u015b\u0107 wymiany na nowe \u2013 r\u00f3wnie\u017c w innym kolorze lub rozmiarze\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/\" \/>\n<meta property=\"og:site_name\" content=\"Aimcontrollers\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/aimcontrollers\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T15:08:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/ps4-red-high.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AimControllerss\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/red-high-ps4-aim-stick\\\/\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/red-high-ps4-aim-stick\\\/\",\"name\":\"Wysoki analog od PS w czerwonym kolorze - Aimcontrollers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/red-high-ps4-aim-stick\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/red-high-ps4-aim-stick\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ps4-red-high.jpg\",\"datePublished\":\"2019-11-15T18:34:26+00:00\",\"dateModified\":\"2022-11-09T15:08:51+00:00\",\"description\":\"Du\u017ca wytrzyma\u0142o\u015b\u0107 ga\u0142ek, a w przypadku ich wytarcia, mo\u017cliwo\u015b\u0107 wymiany na nowe \u2013 r\u00f3wnie\u017c w innym kolorze lub rozmiarze\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/red-high-ps4-aim-stick\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/red-high-ps4-aim-stick\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/red-high-ps4-aim-stick\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ps4-red-high.jpg\",\"contentUrl\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ps4-red-high.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"ps4 red high stick\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/produkt\\\/red-high-ps4-aim-stick\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wysoki analog od PS w czerwonym kolorze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/\",\"name\":\"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC\",\"description\":\"Jedna z najwi\u0119kszych marek dostarczaj\u0105cych w pe\u0142ni modyfikowalne i oryginalne kontrolery.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#organization\",\"name\":\"Aimcontrollers\",\"url\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Aimcontrollers\"},\"image\":{\"@id\":\"https:\\\/\\\/eu.aimcontrollers.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/aimcontrollers\",\"https:\\\/\\\/x.com\\\/AimControllerss\",\"https:\\\/\\\/instagram.com\\\/aimcontrollers\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aimcontrollerspl\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wysoki analog od PS w czerwonym kolorze - Aimcontrollers","description":"Du\u017ca wytrzyma\u0142o\u015b\u0107 ga\u0142ek, a w przypadku ich wytarcia, mo\u017cliwo\u015b\u0107 wymiany na nowe \u2013 r\u00f3wnie\u017c w innym kolorze lub rozmiarze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/","og_locale":"pl_PL","og_type":"article","og_title":"Wysoki analog od PS w czerwonym kolorze","og_description":"Du\u017ca wytrzyma\u0142o\u015b\u0107 ga\u0142ek, a w przypadku ich wytarcia, mo\u017cliwo\u015b\u0107 wymiany na nowe \u2013 r\u00f3wnie\u017c w innym kolorze lub rozmiarze","og_url":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/","og_site_name":"Aimcontrollers","article_publisher":"http:\/\/www.facebook.com\/aimcontrollers","article_modified_time":"2022-11-09T15:08:51+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/ps4-red-high.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AimControllerss","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/","url":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/","name":"Wysoki analog od PS w czerwonym kolorze - Aimcontrollers","isPartOf":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/#primaryimage"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/#primaryimage"},"thumbnailUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/ps4-red-high.jpg","datePublished":"2019-11-15T18:34:26+00:00","dateModified":"2022-11-09T15:08:51+00:00","description":"Du\u017ca wytrzyma\u0142o\u015b\u0107 ga\u0142ek, a w przypadku ich wytarcia, mo\u017cliwo\u015b\u0107 wymiany na nowe \u2013 r\u00f3wnie\u017c w innym kolorze lub rozmiarze","breadcrumb":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/#primaryimage","url":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/ps4-red-high.jpg","contentUrl":"https:\/\/eu.aimcontrollers.com\/wp-content\/uploads\/2019\/11\/ps4-red-high.jpg","width":1000,"height":1000,"caption":"ps4 red high stick"},{"@type":"BreadcrumbList","@id":"https:\/\/eu.aimcontrollers.com\/pl\/produkt\/red-high-ps4-aim-stick\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eu.aimcontrollers.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/eu.aimcontrollers.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Wysoki analog od PS w czerwonym kolorze"}]},{"@type":"WebSite","@id":"https:\/\/eu.aimcontrollers.com\/pl\/#website","url":"https:\/\/eu.aimcontrollers.com\/pl\/","name":"AimControllers - The most affordable competitive controllers for Xbox, PlayStation and PC","description":"Jedna z najwi\u0119kszych marek dostarczaj\u0105cych w pe\u0142ni modyfikowalne i oryginalne kontrolery.","publisher":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eu.aimcontrollers.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/eu.aimcontrollers.com\/pl\/#organization","name":"Aimcontrollers","url":"https:\/\/eu.aimcontrollers.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/eu.aimcontrollers.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Aimcontrollers"},"image":{"@id":"https:\/\/eu.aimcontrollers.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/aimcontrollers","https:\/\/x.com\/AimControllerss","https:\/\/instagram.com\/aimcontrollers\/","https:\/\/www.youtube.com\/user\/aimcontrollerspl\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/product\/1000614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/media\/1000441"}],"wp:attachment":[{"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/media?parent=1000614"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/product_brand?post=1000614"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/product_cat?post=1000614"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/product_tag?post=1000614"},{"taxonomy":"misspellings","embeddable":true,"href":"https:\/\/eu.aimcontrollers.com\/pl\/wp-json\/wp\/v2\/misspellings?post=1000614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}